{"id":16250,"date":"2026-02-15T22:58:51","date_gmt":"2026-02-15T20:58:51","guid":{"rendered":"https:\/\/stoffega.com\/?post_type=product&#038;p=16250"},"modified":"2026-02-15T22:59:38","modified_gmt":"2026-02-15T20:59:38","slug":"blaue-linien-3-3-2-2-2-3-2-2-2-2-2-3-2-2-2-2-2-2-2-2-2-2-2-2-3-2-2-2-2-2-2-2-2","status":"publish","type":"product","link":"https:\/\/stoffega.com\/en\/product\/blaue-linien-3-3-2-2-2-3-2-2-2-2-2-3-2-2-2-2-2-2-2-2-2-2-2-2-3-2-2-2-2-2-2-2-2","title":{"rendered":"St\u00e4dte"},"content":{"rendered":"<p>Meine Jausensackerln sind innen mit beschichtetem Baumwollstoff gearbeitet. Dadurch kann man \u00a0gut &#8211; und ohne weitere Verpackung &#8211; Obst, Gem\u00fcse, Jausenbrote, Joghurt und andere Lebensmittel drin verstauen und braucht daheim den Beutel nur feucht auswischen oder auch unter die Wasserleitung halten, abtrocknen und schon ist er wieder einsatzbereit.<\/p>\n<p>Als Verschluss dient ein gro\u00dfer Knopf mit einem Gummiband und alternativ &#8211; sollte man den ganzen Beutel n\u00fctzen wollen, sind am oberen Rand zwei kleine Druckkn\u00f6pfe.<\/p>\n<p>Nat\u00fcrlich kann dieses T\u00e4schchen auch f\u00fcr Kosmetik, feuchte Badesachen oder \u00c4hnliches verwendet werden.<\/p>\n<p>Nat\u00fcrlich kannst du das Jausensackerl auch bei 30 Grad in der Waschmaschine waschen.<\/p>\n<p><!--more--><\/p>\n<p><!--more--><\/p>","protected":false},"excerpt":{"rendered":"<p><span>handgefertigt aus hochwertigen Baumwollstoffen, gewachster Baumwolle und wunderbar weichen Essex-Leinen<\/span><\/p>\n<p>Gr\u00f6\u00dfe: ca. 20cm x 25cm (in geschlossenem Zustand 20cm x 17cm)<\/p>","protected":false},"featured_media":16251,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[144],"product_tag":[192,191,193,199,194,200,195,196,197,198],"class_list":{"0":"post-16250","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-jausensackerl","7":"product_tag-abwaschbar","8":"product_tag-jause","9":"product_tag-jausenbeutel","10":"product_tag-jausendose","11":"product_tag-jausensackerl","12":"product_tag-lebensmittelverpackung","13":"product_tag-nachhaltig","14":"product_tag-nachhaltigkeit","15":"product_tag-nowaste","16":"product_tag-verpackung","18":"first","19":"instock","20":"shipping-taxable","21":"purchasable","22":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/stoffega.com\/en\/wp-json\/wp\/v2\/product\/16250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stoffega.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stoffega.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/stoffega.com\/en\/wp-json\/wp\/v2\/comments?post=16250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stoffega.com\/en\/wp-json\/wp\/v2\/media\/16251"}],"wp:attachment":[{"href":"https:\/\/stoffega.com\/en\/wp-json\/wp\/v2\/media?parent=16250"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/stoffega.com\/en\/wp-json\/wp\/v2\/product_brand?post=16250"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stoffega.com\/en\/wp-json\/wp\/v2\/product_cat?post=16250"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stoffega.com\/en\/wp-json\/wp\/v2\/product_tag?post=16250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}